{"id":441,"date":"2017-06-08T10:54:52","date_gmt":"2017-06-08T10:54:52","guid":{"rendered":"https:\/\/demo-content.kaliumtheme.com\/travel\/?post_type=portfolio&#038;p=441"},"modified":"2025-04-09T11:37:48","modified_gmt":"2025-04-09T11:37:48","slug":"birdwatching","status":"publish","type":"portfolio","link":"https:\/\/set.am\/de\/portfolio\/birdwatching\/","title":{"rendered":"Vogelbeobachtungstour"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p><\/p>\n<p class=\"Standard\"><span lang=\"DE\" style=\"font-family: 'Arial',sans-serif;\">349 Vogelarten, 18 der 29 Ordnungen und 58 der insgesamt 187 Vogelfamilien. Armenien ist ein Traum f\u00fcr jeden Vogelbeobachter oder Ornithologen. Im und nahe des CWR k\u00f6nnen Sie V\u00f6gel wie den Mongolengimpel, den W\u00fcstengimpel, die Grauhelmammer und verschiedene Arten von Geiern, Seev\u00f6geln, Wasserv\u00f6geln und Enten beobachten. Unsere Zugv\u00f6gel kommen teilweise aus entlegenen L\u00e4ndern, beispielsweise aus S\u00fcdafrika. Wenn Sie also zur richtigen Jahreszeit hier sind, kann unser erfahrener Vogelf\u00fchrer Sie auf diese exquisiten V\u00f6gel hinweisen. W\u00e4hrend der Vogelbeobachtung werden Sie sicherlich auch auf viele andere in Armenien heimische Wildtierarten sto\u00dfen, sodass Ihr Aufenthalt bei uns mit wunderbaren, lebhaften Begegnungen in der freien Natur gef\u00fcllt sein wird.<\/span><\/p>\n<h3 class=\"Standard\"><strong><span lang=\"DE\" style=\"font-family: 'Arial',sans-serif;\">Preis<\/span><\/strong><\/h3>\n<p class=\"Standard\"><strong><span lang=\"DE\" style=\"font-family: 'Arial',sans-serif;\">AMD 70.000 &#8211; Ganzer Tag (7 Stunden) \/ pro Person (mit einem Ornithologen)<\/span><\/strong><\/p>\n<p><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>349 Vogelarten, 18 der 29 Ordnungen und 58 der insgesamt 187 Vogelfamilien. Armenien ist ein Traum f\u00fcr jeden Vogelbeobachter oder Ornithologen. Im und nahe des CWR k\u00f6nnen Sie V\u00f6gel wie den Mongolengimpel, den W\u00fcstengimpel, die Grauhelmammer und verschiedene Arten von Geiern, Seev\u00f6geln, Wasserv\u00f6geln und Enten beobachten. Unsere Zugv\u00f6gel kommen teilweise aus entlegenen L\u00e4ndern, beispielsweise aus&hellip;<\/p>\n","protected":false},"author":5,"featured_media":2694,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[2],"portfolio_tag":[],"class_list":["post-441","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-activities"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vogelbeobachtungstour - SET<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/set.am\/de\/portfolio\/birdwatching\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vogelbeobachtungstour - SET\" \/>\n<meta property=\"og:description\" content=\"349 Vogelarten, 18 der 29 Ordnungen und 58 der insgesamt 187 Vogelfamilien. Armenien ist ein Traum f\u00fcr jeden Vogelbeobachter oder Ornithologen. Im und nahe des CWR k\u00f6nnen Sie V\u00f6gel wie den Mongolengimpel, den W\u00fcstengimpel, die Grauhelmammer und verschiedene Arten von Geiern, Seev\u00f6geln, Wasserv\u00f6geln und Enten beobachten. Unsere Zugv\u00f6gel kommen teilweise aus entlegenen L\u00e4ndern, beispielsweise aus&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/set.am\/de\/portfolio\/birdwatching\/\" \/>\n<meta property=\"og:site_name\" content=\"SET\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SET.SunChild.EcoTours\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-09T11:37:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/set.am\/wp-content\/uploads\/2017\/06\/bird_featimage.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"621\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/set.am\/de\/portfolio\/birdwatching\/\",\"url\":\"https:\/\/set.am\/de\/portfolio\/birdwatching\/\",\"name\":\"Vogelbeobachtungstour - SET\",\"isPartOf\":{\"@id\":\"https:\/\/set.am\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/set.am\/de\/portfolio\/birdwatching\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/set.am\/portfolio\/birdwatching\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/set.am\/wp-content\/uploads\/2017\/06\/bird_featimage.jpg\",\"datePublished\":\"2017-06-08T10:54:52+00:00\",\"dateModified\":\"2025-04-09T11:37:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/set.am\/de\/portfolio\/birdwatching\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\/\/set.am\/de\/portfolio\/birdwatching\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/set.am\/de\/portfolio\/birdwatching\/#primaryimage\",\"url\":\"https:\/\/set.am\/wp-content\/uploads\/2017\/06\/bird_featimage.jpg\",\"contentUrl\":\"https:\/\/set.am\/wp-content\/uploads\/2017\/06\/bird_featimage.jpg\",\"width\":1000,\"height\":621},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/set.am\/de\/portfolio\/birdwatching\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\/\/set.am\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\/\/set.am\/de\/portfolio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Birdwatching\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/set.am\/de\/#website\",\"url\":\"https:\/\/set.am\/de\/\",\"name\":\"SET\",\"description\":\"SunChild Eco tours\",\"publisher\":{\"@id\":\"https:\/\/set.am\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/set.am\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/set.am\/de\/#organization\",\"name\":\"SET\",\"url\":\"https:\/\/set.am\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/set.am\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/set.am\/wp-content\/uploads\/2025\/04\/set.webp\",\"contentUrl\":\"https:\/\/set.am\/wp-content\/uploads\/2025\/04\/set.webp\",\"width\":220,\"height\":181,\"caption\":\"SET\"},\"image\":{\"@id\":\"https:\/\/set.am\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SET.SunChild.EcoTours\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vogelbeobachtungstour - SET","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/set.am\/de\/portfolio\/birdwatching\/","og_locale":"de_DE","og_type":"article","og_title":"Vogelbeobachtungstour - SET","og_description":"349 Vogelarten, 18 der 29 Ordnungen und 58 der insgesamt 187 Vogelfamilien. Armenien ist ein Traum f\u00fcr jeden Vogelbeobachter oder Ornithologen. Im und nahe des CWR k\u00f6nnen Sie V\u00f6gel wie den Mongolengimpel, den W\u00fcstengimpel, die Grauhelmammer und verschiedene Arten von Geiern, Seev\u00f6geln, Wasserv\u00f6geln und Enten beobachten. Unsere Zugv\u00f6gel kommen teilweise aus entlegenen L\u00e4ndern, beispielsweise aus&hellip;","og_url":"https:\/\/set.am\/de\/portfolio\/birdwatching\/","og_site_name":"SET","article_publisher":"https:\/\/www.facebook.com\/SET.SunChild.EcoTours","article_modified_time":"2025-04-09T11:37:48+00:00","og_image":[{"width":1000,"height":621,"url":"https:\/\/set.am\/wp-content\/uploads\/2017\/06\/bird_featimage.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/set.am\/de\/portfolio\/birdwatching\/","url":"https:\/\/set.am\/de\/portfolio\/birdwatching\/","name":"Vogelbeobachtungstour - SET","isPartOf":{"@id":"https:\/\/set.am\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/set.am\/de\/portfolio\/birdwatching\/#primaryimage"},"image":{"@id":"https:\/\/set.am\/portfolio\/birdwatching\/#primaryimage"},"thumbnailUrl":"https:\/\/set.am\/wp-content\/uploads\/2017\/06\/bird_featimage.jpg","datePublished":"2017-06-08T10:54:52+00:00","dateModified":"2025-04-09T11:37:48+00:00","breadcrumb":{"@id":"https:\/\/set.am\/de\/portfolio\/birdwatching\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/set.am\/de\/portfolio\/birdwatching\/"]]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/set.am\/de\/portfolio\/birdwatching\/#primaryimage","url":"https:\/\/set.am\/wp-content\/uploads\/2017\/06\/bird_featimage.jpg","contentUrl":"https:\/\/set.am\/wp-content\/uploads\/2017\/06\/bird_featimage.jpg","width":1000,"height":621},{"@type":"BreadcrumbList","@id":"https:\/\/set.am\/de\/portfolio\/birdwatching\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/set.am\/de\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/set.am\/de\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Birdwatching"}]},{"@type":"WebSite","@id":"https:\/\/set.am\/de\/#website","url":"https:\/\/set.am\/de\/","name":"SET","description":"SunChild Eco tours","publisher":{"@id":"https:\/\/set.am\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/set.am\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/set.am\/de\/#organization","name":"SET","url":"https:\/\/set.am\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/set.am\/de\/#\/schema\/logo\/image\/","url":"https:\/\/set.am\/wp-content\/uploads\/2025\/04\/set.webp","contentUrl":"https:\/\/set.am\/wp-content\/uploads\/2025\/04\/set.webp","width":220,"height":181,"caption":"SET"},"image":{"@id":"https:\/\/set.am\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SET.SunChild.EcoTours"]}]}},"_links":{"self":[{"href":"https:\/\/set.am\/de\/wp-json\/wp\/v2\/portfolio\/441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/set.am\/de\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/set.am\/de\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/set.am\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/set.am\/de\/wp-json\/wp\/v2\/comments?post=441"}],"version-history":[{"count":2,"href":"https:\/\/set.am\/de\/wp-json\/wp\/v2\/portfolio\/441\/revisions"}],"predecessor-version":[{"id":3968,"href":"https:\/\/set.am\/de\/wp-json\/wp\/v2\/portfolio\/441\/revisions\/3968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/set.am\/de\/wp-json\/wp\/v2\/media\/2694"}],"wp:attachment":[{"href":"https:\/\/set.am\/de\/wp-json\/wp\/v2\/media?parent=441"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/set.am\/de\/wp-json\/wp\/v2\/portfolio_category?post=441"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/set.am\/de\/wp-json\/wp\/v2\/portfolio_tag?post=441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}